{"id":1486,"count":1,"description":"","link":"https:\/\/biocontroltechnologies.com\/de\/tag\/rhizocnew\/","name":"RhizocNEW","slug":"rhizocnew","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>RhizocNEW archivos | Biocontrol Technologies<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/biocontroltechnologies.com\/de\/tag\/rhizocnew\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"RhizocNEW archivos | Biocontrol Technologies\" \/>\n<meta property=\"og:url\" content=\"https:\/\/biocontroltechnologies.com\/de\/tag\/rhizocnew\/\" \/>\n<meta property=\"og:site_name\" content=\"Biocontrol Technologies\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/biocontroltechnologies.com\\\/de\\\/tag\\\/rhizocnew\\\/\",\"url\":\"https:\\\/\\\/biocontroltechnologies.com\\\/de\\\/tag\\\/rhizocnew\\\/\",\"name\":\"RhizocNEW archivos | Biocontrol Technologies\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/biocontroltechnologies.com\\\/de\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/biocontroltechnologies.com\\\/de\\\/tag\\\/rhizocnew\\\/#breadcrumb\"},\"inLanguage\":\"de\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/biocontroltechnologies.com\\\/de\\\/tag\\\/rhizocnew\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/biocontroltechnologies.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"RhizocNEW\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/biocontroltechnologies.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/biocontroltechnologies.com\\\/de\\\/\",\"name\":\"Biocontrol Technologies\",\"description\":\"Abordando las enfermedades para transformar la agricultura.\",\"alternateName\":\"Biocontrol Technologies\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/biocontroltechnologies.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"RhizocNEW archivos | Biocontrol Technologies","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/biocontroltechnologies.com\/de\/tag\/rhizocnew\/","og_locale":"de_DE","og_type":"article","og_title":"RhizocNEW archivos | Biocontrol Technologies","og_url":"https:\/\/biocontroltechnologies.com\/de\/tag\/rhizocnew\/","og_site_name":"Biocontrol Technologies","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/biocontroltechnologies.com\/de\/tag\/rhizocnew\/","url":"https:\/\/biocontroltechnologies.com\/de\/tag\/rhizocnew\/","name":"RhizocNEW archivos | Biocontrol Technologies","isPartOf":{"@id":"https:\/\/biocontroltechnologies.com\/de\/#website"},"breadcrumb":{"@id":"https:\/\/biocontroltechnologies.com\/de\/tag\/rhizocnew\/#breadcrumb"},"inLanguage":"de"},{"@type":"BreadcrumbList","@id":"https:\/\/biocontroltechnologies.com\/de\/tag\/rhizocnew\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/biocontroltechnologies.com\/de\/"},{"@type":"ListItem","position":2,"name":"RhizocNEW"}]},{"@type":"WebSite","@id":"https:\/\/biocontroltechnologies.com\/de\/#website","url":"https:\/\/biocontroltechnologies.com\/de\/","name":"Biocontrol Technologies","description":"Abordando las enfermedades para transformar la agricultura.","alternateName":"Biocontrol Technologies","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/biocontroltechnologies.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/biocontroltechnologies.com\/de\/wp-json\/wp\/v2\/tags\/1486","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/biocontroltechnologies.com\/de\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/biocontroltechnologies.com\/de\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/biocontroltechnologies.com\/de\/wp-json\/wp\/v2\/posts?tags=1486"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}